{"id":1922,"date":"2023-02-28T10:34:49","date_gmt":"2023-02-28T09:34:49","guid":{"rendered":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/?p=1922"},"modified":"2023-02-28T10:35:42","modified_gmt":"2023-02-28T09:35:42","slug":"dia-de-la-paz","status":"publish","type":"post","link":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/dia-de-la-paz\/","title":{"rendered":"D\u00cdA DE LA PAZ"},"content":{"rendered":"\n<p>Este a\u00f1o celebramos el d\u00eda de la paz con una edici\u00f3n informativa muy especial, un telediario de buenas noticias que nuestros peque\u00f1as y peque\u00f1os redactores emitieron desde la ludoteca El Desv\u00e1n. A continuaci\u00f3n, salimos a las calles de los Logro\u00f1o a repartir pedacitos de paz: pajaritas de papel, piedras pintadas y caramelos de la felicidad, realizadas los d\u00edas anteriores con mucha ilusi\u00f3n por todos los socios y socias.<\/p>\n\n\n\n<p>\u00a1Un bonito gesto que las y los viandantes agradecieron, en la tarde g\u00e9lida del 30 de enero!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"773\" height=\"1030\" data-id=\"1925\"  src=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04-773x1030.jpg\" alt=\"\" class=\"wp-image-1925\" srcset=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04-773x1030.jpg 773w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04-225x300.jpg 225w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04-768x1024.jpg 768w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04-1152x1536.jpg 1152w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04-1125x1500.jpg 1125w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04-529x705.jpg 529w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-05-04.jpg 1536w\" sizes=\"(max-width: 773px) 100vw, 773px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1030\" height=\"773\" data-id=\"1926\"  src=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31-1030x773.jpg\" alt=\"\" class=\"wp-image-1926\" srcset=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31-1030x773.jpg 1030w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31-300x225.jpg 300w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31-768x576.jpg 768w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31-1536x1152.jpg 1536w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31-1500x1125.jpg 1500w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31-705x529.jpg 705w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-18-03-31.jpg 2048w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"480\" height=\"640\" data-id=\"1923\"  src=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-19-10-46.jpg\" alt=\"\" class=\"wp-image-1923\" srcset=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-19-10-46.jpg 480w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-19-10-46-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"640\" height=\"480\" data-id=\"1924\"  src=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-19-10-47.jpg\" alt=\"\" class=\"wp-image-1924\" srcset=\"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-19-10-47.jpg 640w, https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-30-19-10-47-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o celebramos el d\u00eda de la paz con una edici\u00f3n informativa muy especial, un telediario de buenas noticias que nuestros peque\u00f1as y peque\u00f1os redactores emitieron desde la ludoteca El Desv\u00e1n. A continuaci\u00f3n, salimos a las calles de los Logro\u00f1o a repartir pedacitos de paz: pajaritas de papel, piedras pintadas y caramelos de la felicidad, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/posts\/1922"}],"collection":[{"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/comments?post=1922"}],"version-history":[{"count":1,"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/posts\/1922\/revisions"}],"predecessor-version":[{"id":1927,"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/posts\/1922\/revisions\/1927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/media\/1923"}],"wp:attachment":[{"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/media?parent=1922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/categories?post=1922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--ludotecaslogroo-crb.es\/el_desvan\/wp-json\/wp\/v2\/tags?post=1922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}